{"id":38,"count":0,"description":"","link":"https:\/\/www.kingknhardwear.com\/ar\/product-category\/drawer-slides\/concealed-drawer-slides\/","name":"concealed-drawer-slides","slug":"concealed-drawer-slides","taxonomy":"product_cat","parent":16,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.3 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kingknhardwear.com\/ar\/product-category\/drawer-slides\/concealed-drawer-slides\/\" \/>\n<meta property=\"og:site_name\" content=\"kingknhardwear\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/\",\"url\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/\",\"name\":\"concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear\",\"isPartOf\":{\"@id\":\"https:\/\/www.kingknhardwear.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kingknhardwear.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drawer Slides\",\"item\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"concealed-drawer-slides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kingknhardwear.com\/#website\",\"url\":\"https:\/\/www.kingknhardwear.com\/\",\"name\":\"kingknhardwear\",\"description\":\"A Quality Choice for Home Furniture\",\"publisher\":{\"@id\":\"https:\/\/www.kingknhardwear.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kingknhardwear.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ar\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.kingknhardwear.com\/#organization\",\"name\":\"kingknhardwear\",\"url\":\"https:\/\/www.kingknhardwear.com\/\",\"logo\":{\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo\",\"url\":\"https:\/\/www.kingknhardwear.com\/wp-content\/uploads\/2024\/05\/logo312.png\",\"contentUrl\":\"https:\/\/www.kingknhardwear.com\/wp-content\/uploads\/2024\/05\/logo312.png\",\"width\":350,\"height\":100,\"caption\":\"kingknhardwear\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ar_AR","og_type":"article","og_title":"concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear","og_url":"https:\/\/www.kingknhardwear.com\/ar\/product-category\/drawer-slides\/concealed-drawer-slides\/","og_site_name":"kingknhardwear","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/","url":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/","name":"concealed-drawer-slides \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - kingknhardwear","isPartOf":{"@id":"https:\/\/www.kingknhardwear.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kingknhardwear.com\/"},{"@type":"ListItem","position":2,"name":"Drawer Slides","item":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/"},{"@type":"ListItem","position":3,"name":"concealed-drawer-slides"}]},{"@type":"WebSite","@id":"https:\/\/www.kingknhardwear.com\/#website","url":"https:\/\/www.kingknhardwear.com\/","name":"kingknhardwear","description":"A Quality Choice for Home Furniture","publisher":{"@id":"https:\/\/www.kingknhardwear.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kingknhardwear.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ar"},{"@type":["Organization","Place"],"@id":"https:\/\/www.kingknhardwear.com\/#organization","name":"kingknhardwear","url":"https:\/\/www.kingknhardwear.com\/","logo":{"@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.kingknhardwear.com\/product-category\/drawer-slides\/concealed-drawer-slides\/#local-main-organization-logo","url":"https:\/\/www.kingknhardwear.com\/wp-content\/uploads\/2024\/05\/logo312.png","contentUrl":"https:\/\/www.kingknhardwear.com\/wp-content\/uploads\/2024\/05\/logo312.png","width":350,"height":100,"caption":"kingknhardwear"}]}},"_links":{"self":[{"href":"https:\/\/www.kingknhardwear.com\/ar\/wp-json\/wp\/v2\/product_cat\/38"}],"collection":[{"href":"https:\/\/www.kingknhardwear.com\/ar\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.kingknhardwear.com\/ar\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.kingknhardwear.com\/ar\/wp-json\/wp\/v2\/product_cat\/16"}],"wp:post_type":[{"href":"https:\/\/www.kingknhardwear.com\/ar\/wp-json\/wp\/v2\/product?product_cat=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}